{"id":1038,"count":1,"description":"","link":"https:\/\/eshop.macsales.com\/owc-radio\/tag\/matt-balcerek\/","name":"Matt Balcerek","slug":"matt-balcerek","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/eshop.macsales.com\/owc-radio\/wp-json\/wp\/v2\/tags\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eshop.macsales.com\/owc-radio\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eshop.macsales.com\/owc-radio\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eshop.macsales.com\/owc-radio\/wp-json\/wp\/v2\/posts?tags=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}