{"id":412,"count":1,"description":"","link":"https:\/\/eshop.macsales.com\/owc-radio\/tag\/record-producer\/","name":"record producer","slug":"record-producer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/eshop.macsales.com\/owc-radio\/wp-json\/wp\/v2\/tags\/412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eshop.macsales.com\/owc-radio\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eshop.macsales.com\/owc-radio\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eshop.macsales.com\/owc-radio\/wp-json\/wp\/v2\/posts?tags=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}